{"id":30894,"date":"2025-08-29T11:41:30","date_gmt":"2025-08-29T16:41:30","guid":{"rendered":"https:\/\/littlevillagechamber.org\/?p=30894"},"modified":"2025-08-29T11:41:30","modified_gmt":"2025-08-29T16:41:30","slug":"pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias","status":"publish","type":"post","link":"https:\/\/littlevillagechamber.org\/es\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/","title":{"rendered":"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias"},"content":{"rendered":"<h2 class=\"article-subtitle\">Esta ma\u00f1ana, organizadores del desfile en Pilsen dijeron que, a pesar de la incertidumbre, no dejar\u00e1n que el temor los detenga.<\/h2>\n<p>&nbsp;<\/p>\n<p>A pesar de la incertidumbre, comunidades como Pilsen planean llevar a cabo las celebraciones de las fiestas patrias, pero se anticipa muy diferente a las anteriores.<\/p>\n<p>Esta ma\u00f1ana, organizadores del desfile en Pilsen dijeron que, a pesar de la incertidumbre, no dejar\u00e1n que el temor los detenga.<\/p>\n<p>La comunidad de Pilsen anunci\u00f3 sus planes para celebrar con m\u00fasica, color y orgullo el vig\u00e9simo cuarto desfile anual del D\u00eda de la Independencia de M\u00e9xico. Todo esto, mientras el gobierno de Trump se prepara para usar la base naval de Great Lakes, como centro de operaciones migratorias en Chicago entre el 2 y el 30 de septiembre.<\/p>\n<p>Esta confirmaci\u00f3n ha generado temor entre muchos residentes. \u201cTodos tenemos temor, todos los mexicanos que estamos aqu\u00ed\u201d, dijo Miguel Reynoso, espectador del desfile.<\/p>\n<p>Pero los organizadores aseguran que todo est\u00e1 bajo control y que el evento ser\u00e1 pac\u00edfico y familiar.<\/p>\n<p>\u201cNo nos afecta en nada porque no estamos causando disturbios, estamos celebrando nuestra cultura, nuestras tradiciones y nuestras ra\u00edces\u201d, dijo Vicky Lugo, de la c\u00e1mara de comercio de comerciantes unidos de Pilsen.<\/p>\n<p>Se esperan decenas de voluntarios a lo largo de la ruta para apoyar a los asistentes y garantizar que el evento se desarrolle sin incidentes.<\/p>\n<p>Organizadores de otros eventos, como El Grito en Grant Park y <strong>el desfile en La Villita<\/strong>, tambi\u00e9n confirman que siguen en marcha, y planean dar m\u00e1s informaci\u00f3n al respecto en los pr\u00f3ximos d\u00edas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana, organizadores del desfile en Pilsen dijeron que, a pesar de la incertidumbre, no dejar\u00e1n que el temor los detenga. &nbsp; A pesar de la incertidumbre, comunidades como Pilsen planean llevar a cabo las celebraciones de las fiestas patrias, pero se anticipa muy diferente a las anteriores. Esta ma\u00f1ana, organizadores del desfile en Pilsen [&hellip;]<\/p>\n","protected":false},"author":213,"featured_media":30895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias - Little Village Chamber of Commerce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/littlevillagechamber.org\/es\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias - Little Village Chamber of Commerce\" \/>\n<meta property=\"og:description\" content=\"Esta ma\u00f1ana, organizadores del desfile en Pilsen dijeron que, a pesar de la incertidumbre, no dejar\u00e1n que el temor los detenga. &nbsp; A pesar de la incertidumbre, comunidades como Pilsen planean llevar a cabo las celebraciones de las fiestas patrias, pero se anticipa muy diferente a las anteriores. Esta ma\u00f1ana, organizadores del desfile en Pilsen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/littlevillagechamber.org\/es\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/\" \/>\n<meta property=\"og:site_name\" content=\"Little Village Chamber of Commerce\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-29T16:41:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/Screenshot-2025-08-29-at-11.40.48-AM-1024x573.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Juan Carlos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Carlos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/\"},\"author\":{\"name\":\"Juan Carlos\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#\\\/schema\\\/person\\\/3407b6127674b885823e3884d2881334\"},\"headline\":\"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias\",\"datePublished\":\"2025-08-29T16:41:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/\"},\"wordCount\":285,\"publisher\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/littlevillagechamber.org\\\/wp-content\\\/uploads\\\/Screenshot-2025-08-29-at-11.40.48-AM.png\",\"articleSection\":[\"In other news\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/\",\"url\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/\",\"name\":\"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias - Little Village Chamber of Commerce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/littlevillagechamber.org\\\/wp-content\\\/uploads\\\/Screenshot-2025-08-29-at-11.40.48-AM.png\",\"datePublished\":\"2025-08-29T16:41:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/littlevillagechamber.org\\\/wp-content\\\/uploads\\\/Screenshot-2025-08-29-at-11.40.48-AM.png\",\"contentUrl\":\"https:\\\/\\\/littlevillagechamber.org\\\/wp-content\\\/uploads\\\/Screenshot-2025-08-29-at-11.40.48-AM.png\",\"width\":1522,\"height\":852},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/littlevillagechamber.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#website\",\"url\":\"https:\\\/\\\/littlevillagechamber.org\\\/\",\"name\":\"Little Village Chamber of Commerce\",\"description\":\"Tu Mexico, Tu Chicago!\",\"publisher\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/littlevillagechamber.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#organization\",\"name\":\"Little Village Chamber of Commerce\",\"url\":\"https:\\\/\\\/littlevillagechamber.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/littlevillagechamber.org\\\/wp-content\\\/uploads\\\/LVCC.png\",\"contentUrl\":\"https:\\\/\\\/littlevillagechamber.org\\\/wp-content\\\/uploads\\\/LVCC.png\",\"width\":300,\"height\":257,\"caption\":\"Little Village Chamber of Commerce\"},\"image\":{\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/littlevillagechamber.org\\\/#\\\/schema\\\/person\\\/3407b6127674b885823e3884d2881334\",\"name\":\"Juan Carlos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dbb8bb62a16f84597a78e9714051cf73aa61edd7d20627881ab9e20dcccffd2e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dbb8bb62a16f84597a78e9714051cf73aa61edd7d20627881ab9e20dcccffd2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dbb8bb62a16f84597a78e9714051cf73aa61edd7d20627881ab9e20dcccffd2e?s=96&d=mm&r=g\",\"caption\":\"Juan Carlos\"},\"url\":\"https:\\\/\\\/littlevillagechamber.org\\\/es\\\/author\\\/juancarlos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias - Little Village Chamber of Commerce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/littlevillagechamber.org\/es\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/","og_locale":"es_MX","og_type":"article","og_title":"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias - Little Village Chamber of Commerce","og_description":"Esta ma\u00f1ana, organizadores del desfile en Pilsen dijeron que, a pesar de la incertidumbre, no dejar\u00e1n que el temor los detenga. &nbsp; A pesar de la incertidumbre, comunidades como Pilsen planean llevar a cabo las celebraciones de las fiestas patrias, pero se anticipa muy diferente a las anteriores. Esta ma\u00f1ana, organizadores del desfile en Pilsen [&hellip;]","og_url":"https:\/\/littlevillagechamber.org\/es\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/","og_site_name":"Little Village Chamber of Commerce","article_published_time":"2025-08-29T16:41:30+00:00","og_image":[{"width":1024,"height":573,"url":"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/Screenshot-2025-08-29-at-11.40.48-AM-1024x573.png","type":"image\/png"}],"author":"Juan Carlos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Juan Carlos","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/#article","isPartOf":{"@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/"},"author":{"name":"Juan Carlos","@id":"https:\/\/littlevillagechamber.org\/#\/schema\/person\/3407b6127674b885823e3884d2881334"},"headline":"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias","datePublished":"2025-08-29T16:41:30+00:00","mainEntityOfPage":{"@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/"},"wordCount":285,"publisher":{"@id":"https:\/\/littlevillagechamber.org\/#organization"},"image":{"@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/#primaryimage"},"thumbnailUrl":"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/Screenshot-2025-08-29-at-11.40.48-AM.png","articleSection":["In other news"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/","url":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/","name":"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias - Little Village Chamber of Commerce","isPartOf":{"@id":"https:\/\/littlevillagechamber.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/#primaryimage"},"image":{"@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/#primaryimage"},"thumbnailUrl":"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/Screenshot-2025-08-29-at-11.40.48-AM.png","datePublished":"2025-08-29T16:41:30+00:00","breadcrumb":{"@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/#primaryimage","url":"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/Screenshot-2025-08-29-at-11.40.48-AM.png","contentUrl":"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/Screenshot-2025-08-29-at-11.40.48-AM.png","width":1522,"height":852},{"@type":"BreadcrumbList","@id":"https:\/\/littlevillagechamber.org\/pese-al-temor-por-operativos-migratorios-pilsen-realizara-el-desfile-por-fiestas-patrias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/littlevillagechamber.org\/"},{"@type":"ListItem","position":2,"name":"Pese al temor por operativos migratorios, Pilsen realizar\u00e1 el desfile por Fiestas Patrias"}]},{"@type":"WebSite","@id":"https:\/\/littlevillagechamber.org\/#website","url":"https:\/\/littlevillagechamber.org\/","name":"La C\u00e1mara de Comercio de La Villita","description":"Tu M\u00e9xico, Tu Chicago!","publisher":{"@id":"https:\/\/littlevillagechamber.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/littlevillagechamber.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/littlevillagechamber.org\/#organization","name":"La C\u00e1mara de Comercio de La Villita","url":"https:\/\/littlevillagechamber.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/littlevillagechamber.org\/#\/schema\/logo\/image\/","url":"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/LVCC.png","contentUrl":"https:\/\/littlevillagechamber.org\/wp-content\/uploads\/LVCC.png","width":300,"height":257,"caption":"Little Village Chamber of Commerce"},"image":{"@id":"https:\/\/littlevillagechamber.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/littlevillagechamber.org\/#\/schema\/person\/3407b6127674b885823e3884d2881334","name":"Juan Carlos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/dbb8bb62a16f84597a78e9714051cf73aa61edd7d20627881ab9e20dcccffd2e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dbb8bb62a16f84597a78e9714051cf73aa61edd7d20627881ab9e20dcccffd2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dbb8bb62a16f84597a78e9714051cf73aa61edd7d20627881ab9e20dcccffd2e?s=96&d=mm&r=g","caption":"Juan Carlos"},"url":"https:\/\/littlevillagechamber.org\/es\/author\/juancarlos\/"}]}},"_links":{"self":[{"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/posts\/30894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/users\/213"}],"replies":[{"embeddable":true,"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/comments?post=30894"}],"version-history":[{"count":1,"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/posts\/30894\/revisions"}],"predecessor-version":[{"id":30896,"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/posts\/30894\/revisions\/30896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/media\/30895"}],"wp:attachment":[{"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/media?parent=30894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/categories?post=30894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/littlevillagechamber.org\/es\/wp-json\/wp\/v2\/tags?post=30894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}